{"id":7573,"date":"2023-02-03T23:09:01","date_gmt":"2023-02-04T04:09:01","guid":{"rendered":"https:\/\/www.radiosanctispiritus.cu\/es\/?p=7573"},"modified":"2023-02-03T23:15:17","modified_gmt":"2023-02-04T04:15:17","slug":"retornan-69-migrantes-irregulares-a-cuba","status":"publish","type":"post","link":"https:\/\/www.radiosanctispiritus.cu\/es\/retornan-69-migrantes-irregulares-a-cuba\/","title":{"rendered":"Retornan 69 migrantes irregulares a Cuba"},"content":{"rendered":"<p>Este viernes un vuelo procedente de M\u00e9xico devolvi\u00f3 a Cuba a un grupo de 69 migrantes irregulares, seg\u00fan inform\u00f3 el sitio del Ministerio del Interior (Minint).<\/p>\n<p>Se trata de 46 hombres, 18 mujeres y cinco menores de edad.<\/p>\n<p>Cuatro de estos migrantes abandonaron ilegalmente el pa\u00eds por la v\u00eda mar\u00edtima. El resto viaj\u00f3 de manera legal a pa\u00edses del \u00e1rea y posteriormente se incorporaron a rutas irregulares para tratar de llegar a la frontera de Estados Unidos.<\/p>\n<p>Esta es la tercera operaci\u00f3n desde M\u00e9xico, sumando 195 retornados a la Isla por esa v\u00eda en el presente a\u00f1o.<\/p>\n<p>Durante el 2023 ya son dos mil 112 los migrantes irregulares que han sido regresados en un total de 25 acciones de devoluci\u00f3n desde pa\u00edses con los que Cuba tiene acuerdos migratorios y por el Servicio de Guardacostas de los Estados Unidos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Durante el 2023 ya son dos mil 112 los migrantes irregulares que han sido regresados en un total de 25 acciones de devoluci\u00f3n.<\/p>\n","protected":false},"author":123,"featured_media":7574,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[3,8],"tags":[637,325,491],"coauthors":[],"class_list":["post-7573","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cuba","category-noticia","tag-cuba-emigracion","tag-migracion","tag-salidas-ilegales"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.radiosanctispiritus.cu\/es\/wp-json\/wp\/v2\/posts\/7573","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.radiosanctispiritus.cu\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.radiosanctispiritus.cu\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.radiosanctispiritus.cu\/es\/wp-json\/wp\/v2\/users\/123"}],"replies":[{"embeddable":true,"href":"https:\/\/www.radiosanctispiritus.cu\/es\/wp-json\/wp\/v2\/comments?post=7573"}],"version-history":[{"count":0,"href":"https:\/\/www.radiosanctispiritus.cu\/es\/wp-json\/wp\/v2\/posts\/7573\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.radiosanctispiritus.cu\/es\/wp-json\/wp\/v2\/media\/7574"}],"wp:attachment":[{"href":"https:\/\/www.radiosanctispiritus.cu\/es\/wp-json\/wp\/v2\/media?parent=7573"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.radiosanctispiritus.cu\/es\/wp-json\/wp\/v2\/categories?post=7573"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.radiosanctispiritus.cu\/es\/wp-json\/wp\/v2\/tags?post=7573"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.radiosanctispiritus.cu\/es\/wp-json\/wp\/v2\/coauthors?post=7573"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}