{"id":69703,"date":"2026-05-13T14:55:06","date_gmt":"2026-05-13T18:55:06","guid":{"rendered":"https:\/\/www.radiosanctispiritus.cu\/es\/?p=69703"},"modified":"2026-05-13T15:53:02","modified_gmt":"2026-05-13T19:53:02","slug":"correos-en-cabaiguan-mantiene-sus-servicios-a-pesar-de-la-existencia-de-las-nuevas-plataformas-de-pago","status":"publish","type":"post","link":"https:\/\/www.radiosanctispiritus.cu\/es\/correos-en-cabaiguan-mantiene-sus-servicios-a-pesar-de-la-existencia-de-las-nuevas-plataformas-de-pago\/","title":{"rendered":"Correos en Cabaigu\u00e1n mantiene sus servicios pese a nuevas plataformas de pago"},"content":{"rendered":"<p class=\"ds-markdown-paragraph\"><span class=\"\">A pesar del avance de las plataformas digitales de pago, la Empresa de Correos de Cuba en Cabaigu\u00e1n sostiene sus prestaciones tradicionales y mejora indicadores gracias, fundamentalmente, a la instalaci\u00f3n de paneles solares en sus unidades. As\u00ed lo confirm\u00f3 Juan Carlos P\u00e9rez Ferrer, director de la entidad en el territorio, quien destac\u00f3 el impacto radical de esta tecnolog\u00eda en la agilidad de las operaciones.<\/span><\/p>\n<p class=\"ds-markdown-paragraph\"><span class=\"\">\u00abDesde que se pusieron los paneles solares esto ha sido un cambio radical. Ya no hay colas para comprar un sello, imponer una carta o un giro postal. Anteriormente hab\u00eda hasta tres d\u00edas de atraso en las informaciones por falta de corriente; ahora los cierres contables y los turnos se realizan al d\u00eda\u00bb, explic\u00f3 el directivo. La nueva matriz energ\u00e9tica beneficia a la unidad principal del municipio, a Guayos y a Santa Luc\u00eda, aunque en uno de los puntos persiste la dependencia de la conexi\u00f3n de ETECSA, lo que obliga a trabajar en modo memoria ante interrupciones del servicio.<\/span><\/p>\n<div id=\"attachment_69705\" style=\"width: 456px\" class=\"wp-caption aligncenter\"><img decoding=\"async\" aria-describedby=\"caption-attachment-69705\" class=\"size-full wp-image-69705\" src=\"https:\/\/www.radiosanctispiritus.cu\/es\/wp-content\/uploads\/Correos-de-Cuba-en-Cabaiguan-2.jpg\" alt=\"\" width=\"446\" height=\"336\" \/><p id=\"caption-attachment-69705\" class=\"wp-caption-text\">Foto: La Voz de Cabaigu\u00e1n<\/p><\/div>\n<p class=\"ds-markdown-paragraph\"><span class=\"\">Para paliar el d\u00e9ficit de personal, la empresa implement\u00f3 el pluriempleo y contratos con terceros, medidas que han permitido mantener todas las prestaciones. Asimismo, la venta de paneles solares como nueva l\u00ednea de negocio ha generado ingresos significativos, al punto de que el plan anual ya est\u00e1 cumplido. \u00abEl salario de los trabajadores ha aumentado m\u00e1s de un cuarenta o cincuenta por ciento respecto al que ten\u00edan\u00bb, precis\u00f3 P\u00e9rez Ferrer.<\/span><\/p>\n<p class=\"ds-markdown-paragraph\"><span class=\"\">En cuanto a la distribuci\u00f3n de prensa, la escasez de papel redujo la tirada a una sola vez por semana, limit\u00e1ndose a los peri\u00f3dicos Granma, Trabajadores y el dominical de Juventud Rebelde. No obstante, los suscriptores se mantienen y solo se les cobra por los ejemplares que reciben. Cabaigu\u00e1n goza de una ventaja log\u00edstica: un veh\u00edculo recoge los diarios en Santa Clara y los reparte el martes temprano, a diferencia de otros municipios donde la entrega puede demorar hasta el mi\u00e9rcoles. \u00abSomos privilegiados en ese sentido\u00bb, concluy\u00f3 el director.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Para paliar el d\u00e9ficit de personal, la empresa implement\u00f3 el pluriempleo y contratos con terceros, medidas que han permitido mantener todas las prestaciones<\/p>\n","protected":false},"author":4,"featured_media":69704,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[],"coauthors":[1883],"class_list":["post-69703","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sancti-spiritus"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.radiosanctispiritus.cu\/es\/wp-json\/wp\/v2\/posts\/69703","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.radiosanctispiritus.cu\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.radiosanctispiritus.cu\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.radiosanctispiritus.cu\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.radiosanctispiritus.cu\/es\/wp-json\/wp\/v2\/comments?post=69703"}],"version-history":[{"count":3,"href":"https:\/\/www.radiosanctispiritus.cu\/es\/wp-json\/wp\/v2\/posts\/69703\/revisions"}],"predecessor-version":[{"id":69723,"href":"https:\/\/www.radiosanctispiritus.cu\/es\/wp-json\/wp\/v2\/posts\/69703\/revisions\/69723"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.radiosanctispiritus.cu\/es\/wp-json\/wp\/v2\/media\/69704"}],"wp:attachment":[{"href":"https:\/\/www.radiosanctispiritus.cu\/es\/wp-json\/wp\/v2\/media?parent=69703"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.radiosanctispiritus.cu\/es\/wp-json\/wp\/v2\/categories?post=69703"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.radiosanctispiritus.cu\/es\/wp-json\/wp\/v2\/tags?post=69703"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.radiosanctispiritus.cu\/es\/wp-json\/wp\/v2\/coauthors?post=69703"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}