{"id":69489,"date":"2026-05-11T04:02:32","date_gmt":"2026-05-11T08:02:32","guid":{"rendered":"https:\/\/www.radiosanctispiritus.cu\/es\/?p=69489"},"modified":"2026-05-11T04:10:09","modified_gmt":"2026-05-11T08:10:09","slug":"persisten-en-sancti-spiritus-afectaciones-en-el-abasto-de-agua-a-la-poblacion","status":"publish","type":"post","link":"https:\/\/www.radiosanctispiritus.cu\/es\/persisten-en-sancti-spiritus-afectaciones-en-el-abasto-de-agua-a-la-poblacion\/","title":{"rendered":"Persisten en Sancti Sp\u00edritus afectaciones en el abasto de agua a la poblaci\u00f3n"},"content":{"rendered":"<p>Debido al d\u00e9ficit energ\u00e9tico y la rotura de equipos, la Empresa de Acueducto y Alcantarillado de Sancti Sp\u00edritus contin\u00faa con las afectaciones en el abasto de agua a la poblaci\u00f3n.<\/p>\n<p>Roberto N\u00e1poles Darias, director general de dicha entidad, precisa que por roturas de equipos se afectan 15 mil 867 personas de los municipios de Trinidad, Jatibonico, Yaguajay, Cabaigu\u00e1n, Taguasco y Sancti Sp\u00edritus.<\/p>\n<p>N\u00e1poles Daria hizo referencia al cambio de matriz energ\u00e9tica pendiente a realizar en algunas zonas.<\/p>\n<p>\u00abA pesar del d\u00e9ficit de energ\u00eda en la provincia, la empresa mantiene 91 estaciones de bombeo prestando servicio con mediaci\u00f3n de paneles solares, en las cuales no ha existido problema alguno. De un total de 99, tenemos 8 paralizadas y 91 prestando servicio\u00bb.<\/p>\n<p><iframe src=\"https:\/\/www.ivoox.com\/player_ej_173383049_6_1.html?c1=7a0d0b\" width=\"100%\" height=\"200\" frameborder=\"0\" scrolling=\"no\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Debido al d\u00e9ficit energ\u00e9tico y la rotura de equipos, la Empresa de Acueducto y Alcantarillado de Sancti Sp\u00edritus contin\u00faa con las afectaciones en el abasto de agua a la poblaci\u00f3n.<\/p>\n","protected":false},"author":184,"featured_media":69490,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[8,16,9,1],"tags":[674,1688],"coauthors":[1893],"class_list":["post-69489","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticia","category-economia","category-en-audio","category-sancti-spiritus","tag-abasto-de-agua","tag-acueducto-y-alcantarillado"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.radiosanctispiritus.cu\/es\/wp-json\/wp\/v2\/posts\/69489","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.radiosanctispiritus.cu\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.radiosanctispiritus.cu\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.radiosanctispiritus.cu\/es\/wp-json\/wp\/v2\/users\/184"}],"replies":[{"embeddable":true,"href":"https:\/\/www.radiosanctispiritus.cu\/es\/wp-json\/wp\/v2\/comments?post=69489"}],"version-history":[{"count":2,"href":"https:\/\/www.radiosanctispiritus.cu\/es\/wp-json\/wp\/v2\/posts\/69489\/revisions"}],"predecessor-version":[{"id":69492,"href":"https:\/\/www.radiosanctispiritus.cu\/es\/wp-json\/wp\/v2\/posts\/69489\/revisions\/69492"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.radiosanctispiritus.cu\/es\/wp-json\/wp\/v2\/media\/69490"}],"wp:attachment":[{"href":"https:\/\/www.radiosanctispiritus.cu\/es\/wp-json\/wp\/v2\/media?parent=69489"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.radiosanctispiritus.cu\/es\/wp-json\/wp\/v2\/categories?post=69489"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.radiosanctispiritus.cu\/es\/wp-json\/wp\/v2\/tags?post=69489"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.radiosanctispiritus.cu\/es\/wp-json\/wp\/v2\/coauthors?post=69489"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}