{"id":69445,"date":"2026-05-09T11:45:15","date_gmt":"2026-05-09T15:45:15","guid":{"rendered":"https:\/\/www.radiosanctispiritus.cu\/es\/?p=69445"},"modified":"2026-05-09T11:46:11","modified_gmt":"2026-05-09T15:46:11","slug":"putin-siempre-recordaremos-la-hazana-del-pueblo-sovietico","status":"publish","type":"post","link":"https:\/\/www.radiosanctispiritus.cu\/es\/putin-siempre-recordaremos-la-hazana-del-pueblo-sovietico\/","title":{"rendered":"Putin: Siempre recordaremos la haza\u00f1a del pueblo sovi\u00e9tico"},"content":{"rendered":"<p>Para nosotros, es una cuesti\u00f3n de honor preservar la memoria de los acontecimientos de la Gran Guerra Patria, de su historia aut\u00e9ntica y sus h\u00e9roes verdaderos, asegur\u00f3 este s\u00e1bado Vladimir Putin, presidente de la Federaci\u00f3n Rusa, en ocasi\u00f3n del 81 aniversario del D\u00eda de la Victoria.<\/p>\n<p>Putin pronunci\u00f3 un discurso en el que felicit\u00f3 a los ciudadanos rusos por la festividad.<\/p>\n<p>Durante su intervenci\u00f3n, calific\u00f3 el inicio de la Gran Guerra Patria como una de las fechas m\u00e1s tristes de la historia de Rusia.<\/p>\n<p>Putin subray\u00f3 que fue el pueblo de la URSS quien salv\u00f3 al mundo del nazismo.<\/p>\n<p>El mandatario indic\u00f3 que los participantes de la operaci\u00f3n militar especial enfrentan una fuerza agresiva con armamento y apoyo del bloque de la OTAN.<\/p>\n<p>En la marcha participaron unidades de diversas ramas de las Fuerzas Armadas de Rusia, academias militares y combatientes de la operaci\u00f3n militar especial en Ucrania.<\/p>\n<p>Tras el desfile terrestre, aviones surcaron el cielo de Mosc\u00fa en homenaje a la victoria.<\/p>\n<p>Al concluir, Putin y l\u00edderes extranjeros depositaron coronas de flores en la Tumba del Soldado Desconocido y guardaron un minuto de silencio por los ca\u00eddos.<\/p>\n<p><strong>Discurso\u00a0del Presidente de Rusia con motivo del D\u00eda de la Victoria<\/strong><\/p>\n<p><em>Mosc\u00fa, 9 de mayo de 2026<\/em><br \/>\n<strong>Vlad\u00edmir Putin:<\/strong>\u00a0\u00a1Les felicito por el\u00a0<strong>D\u00eda de la Victoria<\/strong>, nuestra fiesta sagrada, luminosa y m\u00e1s importante!<\/p>\n<p><strong>Honramos sagradamente los preceptos y el legado de los soldados de la Victoria<\/strong>. El cuidado de la Patria une a todo nuestro pa\u00eds, a todo el pueblo de Rusia. Para nosotros, es una cuesti\u00f3n de honor preservar la memoria de los acontecimientos de la Gran Guerra Patria, de su historia aut\u00e9ntica y sus h\u00e9roes verdaderos.<\/p>\n<p><strong>Siempre recordaremos la haza\u00f1a del pueblo sovi\u00e9tico<\/strong>, lo que fue precisamente \u00e9l quien hizo la contribuci\u00f3n decisiva a la derrota del nazismo, salv\u00f3 a su pa\u00eds, salv\u00f3 al mundo, puso fin al mal total e implacable, devolvi\u00f3 la soberan\u00eda a aquellos Estados que se rindieron ante la Alemania hitleriana y se convirtieron en c\u00f3mplices sumisos de sus cr\u00edmenes. &lt;\u2026&gt;<\/p>\n<p><strong>El 22 de junio de 1941 es una de las fechas m\u00e1s tr\u00e1gicas y dolorosas de nuestra historia<\/strong>. Este a\u00f1o se cumplir\u00e1n 85 a\u00f1os del\u00a0inicio de la Gran Guerra Patria.<\/p>\n<p>Los nazis\u00a0<strong>agredieron traicioneramente\u00a0<\/strong>a la Uni\u00f3n Sovi\u00e9tica, planearon la conquista del pa\u00eds y sus riqu\u00edsimos recursos, la destrucci\u00f3n total de la cultura, nuestro patrimonio hist\u00f3rico y, finalmente, el exterminio, la esclavizaci\u00f3n y el\u00a0<strong>genocidio de todo el pueblo sovi\u00e9tico multi\u00e9tnico<\/strong>. S\u00ed, de todos los pueblos, naciones y etnias de la Uni\u00f3n Sovi\u00e9tica.<\/p>\n<p><strong>Para implementar estos fines criminales se reunieron fuerzas de toda Europa.<\/strong>\u00a0Parec\u00eda que los estrategas nazis lo hab\u00edan calculado todo meticulosamente. Todo menos una cosa: lo que se llama el car\u00e1cter ruso y la fortaleza espiritual del pueblo sovi\u00e9tico. &lt;\u2026&gt;<\/p>\n<p><strong>Inclinamos nuestras cabezas ante los ca\u00eddos en combate.<\/strong>\u00a0Ante aquellos que fueron torturados en la ocupaci\u00f3n y en cautiverio, que murieron de hambre durante el asedio de Leningrado, en otras ciudades y pueblos asediados. Ante todos los que dieron su vida por la Patria, por Rusia.\u00a0<strong>Inclinamos nuestras cabezas ante la memoria de hijos, hijas, padres, madres, abuelos, bisabuelos, esposos, esposas, hermanos, hermanas, familiares y amigos.<\/strong><\/p>\n<p><strong>La gran haza\u00f1a de la generaci\u00f3n vencedora inspira a los soldados\u00a0<\/strong>que hoy cumplen con las tareas de la operaci\u00f3n militar especial. Ellos se enfrentan a una fuerza agresiva que est\u00e1 armada y respaldada por todo el bloque de la OTAN.<\/p>\n<p><strong>A pesar de esto, nuestros h\u00e9roes avanzan.<\/strong><\/p>\n<p><strong>Junto a los soldados rusos est\u00e1n los obreros, dise\u00f1adores, ingenieros, cient\u00edficos e inventores.<\/strong>\u00a0Ellos contin\u00faan las tradiciones de sus predecesores, apoy\u00e1ndose en la experiencia b\u00e9lica moderna, crean modelos de armamento avanzados y \u00fanicos, y despliegan ampliamente su producci\u00f3n. &lt;\u2026&gt;<\/p>\n<p><strong>Estoy firmemente convencido de que nuestra causa es justa. \u00a1Estamos unidos! \u00a1La Victoria siempre ha sido y siempre ser\u00e1 nuestra!<\/strong><\/p>\n<p><strong>\u00a1Gloria al pueblo vencedor! \u00a1Gloria a los veteranos! \u00a1Gloria a las Fuerzas Armadas de Rusia!<\/strong><\/p>\n<p><strong>\u00a1Felicidades en esta fiesta! \u00a1Feliz D\u00eda de la Victoria! \u00a1Hurra!<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Para nosotros, es una cuesti\u00f3n de honor preservar la memoria de los acontecimientos de la Gran Guerra Patria, de su historia aut\u00e9ntica y sus h\u00e9roes verdaderos, asegur\u00f3 este s\u00e1bado Vladimir Putin, presidente de la Federaci\u00f3n Rusa, en ocasi\u00f3n del 81 aniversario del D\u00eda de la Victoria.<\/p>\n","protected":false},"author":4,"featured_media":69449,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[8,4],"tags":[2378,2149,533],"coauthors":[1883],"class_list":["post-69445","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticia","category-internacionales","tag-fascismo","tag-rusia","tag-vladimir-putin"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.radiosanctispiritus.cu\/es\/wp-json\/wp\/v2\/posts\/69445","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.radiosanctispiritus.cu\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.radiosanctispiritus.cu\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.radiosanctispiritus.cu\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.radiosanctispiritus.cu\/es\/wp-json\/wp\/v2\/comments?post=69445"}],"version-history":[{"count":1,"href":"https:\/\/www.radiosanctispiritus.cu\/es\/wp-json\/wp\/v2\/posts\/69445\/revisions"}],"predecessor-version":[{"id":69450,"href":"https:\/\/www.radiosanctispiritus.cu\/es\/wp-json\/wp\/v2\/posts\/69445\/revisions\/69450"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.radiosanctispiritus.cu\/es\/wp-json\/wp\/v2\/media\/69449"}],"wp:attachment":[{"href":"https:\/\/www.radiosanctispiritus.cu\/es\/wp-json\/wp\/v2\/media?parent=69445"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.radiosanctispiritus.cu\/es\/wp-json\/wp\/v2\/categories?post=69445"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.radiosanctispiritus.cu\/es\/wp-json\/wp\/v2\/tags?post=69445"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.radiosanctispiritus.cu\/es\/wp-json\/wp\/v2\/coauthors?post=69445"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}