{"id":59214,"date":"2025-12-06T17:32:15","date_gmt":"2025-12-06T22:32:15","guid":{"rendered":"https:\/\/www.radiosanctispiritus.cu\/es\/?p=59214"},"modified":"2025-12-06T17:34:12","modified_gmt":"2025-12-06T22:34:12","slug":"ceden-los-gallos-ante-los-lenadores-en-otro-cerrado-juego","status":"publish","type":"post","link":"https:\/\/www.radiosanctispiritus.cu\/es\/ceden-los-gallos-ante-los-lenadores-en-otro-cerrado-juego\/","title":{"rendered":"Ceden los Gallos ante los Le\u00f1adores en otro cerrado juego"},"content":{"rendered":"<p class=\"gmail-western\" lang=\"es-ES\" align=\"justify\"><span style=\"font-family: Arial, sans-serif;\"><span style=\"font-size: large;\">En otro cerrado juego de pelota, en el que Sancti Sp\u00ecritus vendi\u00f3 bien cara su derrota, los Le\u00f1adores de Las Tunas se impusieron <span id=\"OBJ_PREFIX_DWT71_com_zimbra_date\" class=\"Object\" role=\"link\">hoy<\/span> 6 carreras por 5 en el cuarto encuentro de la serie particular entre ambos que transcurre en el Estadio Julio Antonio Mella.<\/span><\/span><\/p>\n<p class=\"gmail-western\" lang=\"es-ES\" align=\"justify\"><span style=\"font-family: Arial, sans-serif;\"><span style=\"font-size: large;\">Los tuneros anotaron una en el primero, Sancti Sp\u00ecritus empat\u00f3 en el segundo y pone el juego 1-1. Los l\u00edderes de esta Serie Nacional hacen racimo de tres anotaciones en el tercer cap\u00edtulo para poner el encuentro 4-1. <\/span><\/span><\/p>\n<p class=\"gmail-western\" lang=\"es-ES\" align=\"justify\"><span style=\"font-family: Arial, sans-serif;\"><span style=\"font-size: large;\">Los nuestros se pegan en el marcador al pisar dos veces el home play en la baja del tercero y el duelo se torna interesante con el marcador 4-3 a favor de los tuneros.<\/span><\/span><\/p>\n<p class=\"gmail-western\" lang=\"es-ES\" align=\"justify\"><span style=\"font-family: Arial, sans-serif;\"><span style=\"font-size: large;\">El abridor yayabero Jos\u00e8 Isaias Grandales abandona el box por molestias en uno de sus pies y en su ayuda viene Yankiel Mauris que maniat\u00f3 a los orientales durante las tres entradas que trabaj\u00f3.<\/span><\/span><\/p>\n<p class=\"gmail-western\" lang=\"es-ES\" align=\"justify\"><span style=\"font-family: Arial, sans-serif;\"><span style=\"font-size: large;\">En el s\u00e9ptimo inning Lazaro Fernandez conecta imparable impulsor al parque derecho y empata el encuentro a cuatro carrera para dejar el escenario listo para que en la parte baja del octavo episodio el junior Frederich Cepeda conect\u00f3 cuadrangular para poner delante a los Gallos 5 carreras por 3.<\/span><\/span><\/p>\n<p class=\"gmail-western\" lang=\"es-ES\" align=\"justify\"><span style=\"font-family: Arial, sans-serif;\"><span style=\"font-size: large;\">En la alta del noveno el le\u00f1ador Yudier Rond\u00f3n le pega cuadrangular de dos carreras por el jard\u00edn izquierdo al relevista espirituano Yanielquis Duardo para decidir el desaf\u00edo con marcador de 6 X 5.<\/span><\/span><\/p>\n<p class=\"gmail-western\" lang=\"es-ES\" align=\"justify\"><span style=\"font-family: Arial, sans-serif;\"><span style=\"font-size: large;\">N\u00f9meros Finales :<\/span><\/span><\/p>\n<p class=\"gmail-western\" lang=\"es-ES\" align=\"justify\"><span style=\"font-family: Arial, sans-serif;\"><span style=\"font-size: large;\">C H E<\/span><\/span><\/p>\n<p class=\"gmail-western\" lang=\"es-ES\" align=\"justify\"><span style=\"font-family: Arial, sans-serif;\"><span style=\"font-size: large;\">LTU 6 12 2<\/span><\/span><\/p>\n<p class=\"gmail-western\" lang=\"es-ES\" align=\"justify\"><span style=\"font-family: Arial, sans-serif;\"><span style=\"font-size: large;\">SSP 5 10 2<\/span><\/span><\/p>\n<p class=\"gmail-western\" lang=\"es-ES\" align=\"justify\"><span style=\"font-family: Arial, sans-serif;\"><span style=\"font-size: large;\">G : Kenier Ferr\u00e0s<\/span><\/span><\/p>\n<p class=\"gmail-western\" lang=\"es-ES\" align=\"justify\"><span style=\"font-family: Arial, sans-serif;\"><span style=\"font-size: large;\">P : Yanielquis Duardo.<\/span><\/span><\/p>\n<p class=\"gmail-western\" lang=\"es-ES\" align=\"justify\"><span style=\"font-family: Arial, sans-serif;\"><span style=\"font-size: large;\">JS : Alberto.P Civil (9)<\/span><\/span><\/p>\n<p class=\"gmail-western\" lang=\"es-ES\" align=\"justify\"><span style=\"font-family: Arial, sans-serif;\"><span style=\"font-size: large;\">Hrs : Frederich Cepeda (JR)<\/span><\/span><\/p>\n<p class=\"gmail-western\" lang=\"es-ES\" align=\"justify\"><span style=\"font-family: Arial, sans-serif;\"><span style=\"font-size: large;\">Yudiel Rond\u00f2n<\/span><\/span><\/p>\n<p class=\"gmail-western\" lang=\"es-ES\" align=\"justify\"><span style=\"font-family: Arial, sans-serif;\"><span style=\"font-size: large;\">Tras este resultado los Le\u00f1adores, a falta de un juego, ya se impusieron en el pareo particular pues archivan tres triunfos con una derrota en los cuatro encuentros efectuados.<\/span><\/span><\/p>\n<p class=\"gmail-western\" lang=\"es-ES\" align=\"justify\"><span style=\"font-family: Arial, sans-serif;\"><span style=\"font-size: large;\">Sancti Sp\u00ecritus presenta balance de 34 victorias con 30 derrotas y los tuneros 38 y 21. Este domingo ser\u00e1 el quinto encuentro de esta serie particular a partir de las 10 de la <span id=\"OBJ_PREFIX_DWT72_com_zimbra_date\" class=\"Object\" role=\"link\">ma\u00f1ana<\/span> con un conjunto yayabero urgido de una victoria.<\/span><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>En otro cerrado juego de pelota, en el que Sancti Sp\u00ecritus vendi\u00f3 bien cara su derrota, los Le\u00f1adores de Las Tunas se impusieron hoy 6 carreras por 5 en el cuarto encuentro de la serie particular entre ambos que transcurre en el Estadio Julio Antonio Mella.<\/p>\n","protected":false},"author":175,"featured_media":25283,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[8,7],"tags":[],"coauthors":[1868],"class_list":["post-59214","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticia","category-deporte"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.radiosanctispiritus.cu\/es\/wp-json\/wp\/v2\/posts\/59214","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.radiosanctispiritus.cu\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.radiosanctispiritus.cu\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.radiosanctispiritus.cu\/es\/wp-json\/wp\/v2\/users\/175"}],"replies":[{"embeddable":true,"href":"https:\/\/www.radiosanctispiritus.cu\/es\/wp-json\/wp\/v2\/comments?post=59214"}],"version-history":[{"count":1,"href":"https:\/\/www.radiosanctispiritus.cu\/es\/wp-json\/wp\/v2\/posts\/59214\/revisions"}],"predecessor-version":[{"id":59215,"href":"https:\/\/www.radiosanctispiritus.cu\/es\/wp-json\/wp\/v2\/posts\/59214\/revisions\/59215"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.radiosanctispiritus.cu\/es\/wp-json\/wp\/v2\/media\/25283"}],"wp:attachment":[{"href":"https:\/\/www.radiosanctispiritus.cu\/es\/wp-json\/wp\/v2\/media?parent=59214"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.radiosanctispiritus.cu\/es\/wp-json\/wp\/v2\/categories?post=59214"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.radiosanctispiritus.cu\/es\/wp-json\/wp\/v2\/tags?post=59214"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.radiosanctispiritus.cu\/es\/wp-json\/wp\/v2\/coauthors?post=59214"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}