{"id":55935,"date":"2025-10-17T15:37:21","date_gmt":"2025-10-17T19:37:21","guid":{"rendered":"https:\/\/www.radiosanctispiritus.cu\/es\/?p=55935"},"modified":"2025-10-17T15:37:21","modified_gmt":"2025-10-17T19:37:21","slug":"la-resurreccion-del-atletismo-cubano","status":"publish","type":"post","link":"https:\/\/www.radiosanctispiritus.cu\/es\/la-resurreccion-del-atletismo-cubano\/","title":{"rendered":"La \u201cresurrecci\u00f3n\u201d del atletismo cubano"},"content":{"rendered":"<p><span style=\"color: #000000;\"> <span style=\"font-family: Tahoma, serif;\"><span style=\"font-size: large;\">El atletismo cubano sali\u00f3 de Tokio con un saldo que merece celebrarse: el oro de Leyanis P\u00e9rez, los bronces de Silinda Morales y L\u00e1zaro Mart\u00ednez, y <\/span><\/span><\/span><span style=\"color: #0000ff;\"><a href=\"https:\/\/worldathletics.org\/competitions\/world-athletics-championships\/tokyo25\/placingtable#_blank\" target=\"_blank\" rel=\"noopener noreferrer nofollow\"><span style=\"color: #000000;\"><span style=\"font-family: Tahoma, serif;\"><span style=\"font-size: large;\">seis finalistas que colocaron a Cuba en el puesto 16 tanto del medallero como de la tabla de puntos, con 32 unidades.<\/span><\/span><\/span><\/a><\/span><\/p>\n<p><span style=\"font-family: Tahoma, serif;\"><span style=\"font-size: large;\">Enfrentarse a lo que m\u00e1s vale y brilla del deporte Rey en el planeta fue todo un reto para los 17 deportistas. De esta forma la Mayor de las Antillas super\u00f3 las dos actuaciones precedentes en eventos del orbe, y regres\u00f3 a lo m\u00e1s alto del podio, algo que no suced\u00eda desde Doha 2019.<\/span><\/span><\/p>\n<p><span style=\"font-family: Tahoma, serif;\"><span style=\"font-size: large;\">Los criterios del comentarista deportivo y especialista Oscar Casta\u00f1eda Rodr\u00edguez y del periodista Joaqu\u00edn G\u00f3mez Serra nos acercan en su podcast Yayabo Deportivo a la realidad actual del atletismo en Cuba<\/span><\/span>.<\/p>\n<p><iframe src=\"https:\/\/www.ivoox.com\/player_ej_160477881_6_1.html?c1=db5749\" width=\"100%\" height=\"200\" frameborder=\"0\" scrolling=\"no\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El atletismo cubano sali\u00f3 de Tokio con un saldo que merece celebrarse: el oro de Leyanis P\u00e9rez, los bronces de Silinda Morales y L\u00e1zaro Mart\u00ednez, y seis finalistas que colocaron a Cuba en el puesto 16 tanto del medallero como de la tabla de puntos, con 32 unidades.<\/p>\n","protected":false},"author":11,"featured_media":55936,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"audio","meta":{"_acf_changed":false,"footnotes":""},"categories":[1145,1123],"tags":[],"coauthors":[1892],"class_list":["post-55935","post","type-post","status-publish","format-audio","has-post-thumbnail","hentry","category-podcast","category-yayabo-deportivo","post_format-post-format-audio"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.radiosanctispiritus.cu\/es\/wp-json\/wp\/v2\/posts\/55935","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.radiosanctispiritus.cu\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.radiosanctispiritus.cu\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.radiosanctispiritus.cu\/es\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/www.radiosanctispiritus.cu\/es\/wp-json\/wp\/v2\/comments?post=55935"}],"version-history":[{"count":1,"href":"https:\/\/www.radiosanctispiritus.cu\/es\/wp-json\/wp\/v2\/posts\/55935\/revisions"}],"predecessor-version":[{"id":55937,"href":"https:\/\/www.radiosanctispiritus.cu\/es\/wp-json\/wp\/v2\/posts\/55935\/revisions\/55937"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.radiosanctispiritus.cu\/es\/wp-json\/wp\/v2\/media\/55936"}],"wp:attachment":[{"href":"https:\/\/www.radiosanctispiritus.cu\/es\/wp-json\/wp\/v2\/media?parent=55935"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.radiosanctispiritus.cu\/es\/wp-json\/wp\/v2\/categories?post=55935"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.radiosanctispiritus.cu\/es\/wp-json\/wp\/v2\/tags?post=55935"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.radiosanctispiritus.cu\/es\/wp-json\/wp\/v2\/coauthors?post=55935"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}