{"id":50689,"date":"2025-07-21T16:21:17","date_gmt":"2025-07-21T20:21:17","guid":{"rendered":"https:\/\/www.radiosanctispiritus.cu\/es\/?p=50689"},"modified":"2025-07-21T16:21:17","modified_gmt":"2025-07-21T20:21:17","slug":"me-encanta-como-lo-oyes-y-el-programa-mexicano","status":"publish","type":"post","link":"https:\/\/www.radiosanctispiritus.cu\/es\/me-encanta-como-lo-oyes-y-el-programa-mexicano\/","title":{"rendered":"\u00abMe encanta Como Lo Oyes y el programa mexicano\u00bb"},"content":{"rendered":"<p class=\"western\" lang=\"en-US\" align=\"justify\"><span style=\"color: #000000;\"><span style=\"font-family: Verdana, sans-serif;\"><span style=\"font-size: large;\"><span lang=\"es-ES\">Con 87 a\u00f1os cumplidos, la abuela Edubina Ram\u00edrez, vecina de la comunidad de Magua, en el municipio de Trinidad, le sonr\u00ede a la vida mientras escucha Radio Sancti Sp\u00edritus y sus programas preferidos \u201cComo lo oyes\u201d y \u201cDe M\u00e9xico sus canciones\u201d. Para \u201cCuchita\u201d, como cari\u00f1osamente le conocen, las plantas ornamentales, los \u00e1rboles frutales de su patio y el cari\u00f1o de sus hijos, bastan para sentirse realizada. Desde la intimidad de su cocina, mientras realiza un sabroso potaje de frijoles negros, esta fiel oyente es feliz a la par de nuestra emisora. Esas y otras confesiones en \u201cDial 80\u201d, un podcast de Yaikel Arias que celebra a las audiencias de una radio \u201ccontempor\u00e1nea en su tradici\u00f3n\u201d.<\/span><\/span><\/span><\/span><\/p>\n<p><iframe src=\"https:\/\/www.ivoox.com\/player_ej_153470686_6_1.html?c1=8c1414\" width=\"100%\" height=\"200\" frameborder=\"0\" scrolling=\"no\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con 87 a\u00f1os cumplidos, la abuela Edubina Ram\u00edrez, vecina de la comunidad de Magua, en el municipio de Trinidad, le sonr\u00ede a la vida mientras escucha Radio Sancti Sp\u00edritus y sus programas preferidos \u201cComo lo oyes\u201d y \u201cDe M\u00e9xico sus canciones\u201d.<\/p>\n","protected":false},"author":4,"featured_media":50690,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"audio","meta":{"_acf_changed":false,"footnotes":""},"categories":[1145,1972],"tags":[],"coauthors":[1883],"class_list":["post-50689","post","type-post","status-publish","format-audio","has-post-thumbnail","hentry","category-podcast","category-dial-80","post_format-post-format-audio"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.radiosanctispiritus.cu\/es\/wp-json\/wp\/v2\/posts\/50689","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.radiosanctispiritus.cu\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.radiosanctispiritus.cu\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.radiosanctispiritus.cu\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.radiosanctispiritus.cu\/es\/wp-json\/wp\/v2\/comments?post=50689"}],"version-history":[{"count":0,"href":"https:\/\/www.radiosanctispiritus.cu\/es\/wp-json\/wp\/v2\/posts\/50689\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.radiosanctispiritus.cu\/es\/wp-json\/wp\/v2\/media\/50690"}],"wp:attachment":[{"href":"https:\/\/www.radiosanctispiritus.cu\/es\/wp-json\/wp\/v2\/media?parent=50689"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.radiosanctispiritus.cu\/es\/wp-json\/wp\/v2\/categories?post=50689"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.radiosanctispiritus.cu\/es\/wp-json\/wp\/v2\/tags?post=50689"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.radiosanctispiritus.cu\/es\/wp-json\/wp\/v2\/coauthors?post=50689"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}