{"id":43646,"date":"2025-03-11T16:08:46","date_gmt":"2025-03-11T20:08:46","guid":{"rendered":"https:\/\/www.radiosanctispiritus.cu\/es\/?p=43646"},"modified":"2025-09-30T12:58:53","modified_gmt":"2025-09-30T16:58:53","slug":"la-era-del-rock-banda-de-hip-hop-beastie-boys","status":"publish","type":"post","link":"https:\/\/www.radiosanctispiritus.cu\/es\/la-era-del-rock-banda-de-hip-hop-beastie-boys\/","title":{"rendered":"Beastie Boys"},"content":{"rendered":"<p>Beastie Boys fue un influyente grupo de hip-hop formado en Nueva York en 1981 por Michael \u201cMike D\u201d Diamond, Adam \u201cMCA\u201d Yauch y Adam \u201cAd-Rock\u201d Horovitz. Originalmente comenzaron como banda de hardcore punk, pero tras el \u00e9xito del sencillo \u201cCooky Puss\u201d en 1983, hicieron una transici\u00f3n completa al rap. Su \u00e1lbum debut Licensed to Ill (1986) fue el primero de hip-hop en alcanzar el n\u00famero uno en Billboard, impulsado por el himno \u201c(You Gotta) Fight for Your Right (To Party!)\u201d<\/p>\n<p>A lo largo de su carrera, lanzaron discos innovadores como Paul\u2019s Boutique (1989), Check Your Head (1992) y Hello Nasty (1998), fusionando g\u00e9neros y redefiniendo el sonido del hip-hop alternativo. Vendieron m\u00e1s de 20 millones de discos en EE. UU. y fueron incluidos en el Sal\u00f3n de la Fama del Rock and Roll en 2012. Ese mismo a\u00f1o, tras la muerte de MCA por c\u00e1ncer, el grupo se disolvi\u00f3, dejando un legado imborrable de creatividad, irreverencia y activismo.<\/p>\n<p><iframe src=\"https:\/\/www.ivoox.com\/player_ej_141385352_6_1.html?c1=daad89\" width=\"100%\" height=\"200\" frameborder=\"0\" scrolling=\"no\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mientras los movimientos p\u00e9lvicos de Elvis Presley provocaban en norteam\u00e9rica una situaci\u00f3n de esc\u00e1ndalo, a partir de 1954 el productor Sam Phillips aseguraba que la primera grabaci\u00f3n del rock and roll ya hab\u00eda sido realizada en sus estudios en 1951. En medio de esta imposible precisi\u00f3n hab\u00eda comenzado la Era del Rock , una estructura h\u00e1bilmente decorada con m\u00faltiples y ef\u00edmeras variantes del pop y fuertemente sostenida por un g\u00e9nero en constante evoluci\u00f3n, el Rock and Roll.<\/p>\n<p>Hoy en La Era del Rock: Beastie Boys\u00a0<\/p>\n","protected":false},"author":4,"featured_media":43647,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"audio","meta":{"_acf_changed":false,"footnotes":""},"categories":[1393,10],"tags":[],"coauthors":[1883],"class_list":["post-43646","post","type-post","status-publish","format-audio","has-post-thumbnail","hentry","category-la-era-del-rock","category-programas-de-radio","post_format-post-format-audio"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.radiosanctispiritus.cu\/es\/wp-json\/wp\/v2\/posts\/43646","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.radiosanctispiritus.cu\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.radiosanctispiritus.cu\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.radiosanctispiritus.cu\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.radiosanctispiritus.cu\/es\/wp-json\/wp\/v2\/comments?post=43646"}],"version-history":[{"count":1,"href":"https:\/\/www.radiosanctispiritus.cu\/es\/wp-json\/wp\/v2\/posts\/43646\/revisions"}],"predecessor-version":[{"id":54880,"href":"https:\/\/www.radiosanctispiritus.cu\/es\/wp-json\/wp\/v2\/posts\/43646\/revisions\/54880"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.radiosanctispiritus.cu\/es\/wp-json\/wp\/v2\/media\/43647"}],"wp:attachment":[{"href":"https:\/\/www.radiosanctispiritus.cu\/es\/wp-json\/wp\/v2\/media?parent=43646"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.radiosanctispiritus.cu\/es\/wp-json\/wp\/v2\/categories?post=43646"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.radiosanctispiritus.cu\/es\/wp-json\/wp\/v2\/tags?post=43646"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.radiosanctispiritus.cu\/es\/wp-json\/wp\/v2\/coauthors?post=43646"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}