{"id":43536,"date":"2025-03-09T03:40:44","date_gmt":"2025-03-09T07:40:44","guid":{"rendered":"https:\/\/www.radiosanctispiritus.cu\/es\/?p=43536"},"modified":"2025-03-09T08:01:52","modified_gmt":"2025-03-09T12:01:52","slug":"como-saber-si-su-hijo-se-ha-acercado-a-las-drogas","status":"publish","type":"post","link":"https:\/\/www.radiosanctispiritus.cu\/es\/como-saber-si-su-hijo-se-ha-acercado-a-las-drogas\/","title":{"rendered":"\u00bfC\u00f3mo saber si su hijo se ha acercado a las drogas?"},"content":{"rendered":"<p>\u00bfC\u00f3mo saber si su hijo tiene indicios de estar consumiendo drogas? \u00bfQu\u00e9 elementos debemos velar en el comportamiento de nuestros adolescentes? <\/p>\n<p>La adolescencia es una etapa muy dif\u00edcil, es la etapa de la vida del ser humano donde m\u00e1s cambios existen, donde hay cambios biol\u00f3gicos, ps\u00edquicos y sociales, una etapa de alta vulnerabilidad, una etapa donde el criterio propio todav\u00eda no est\u00e1 de todo formado y donde el grupo es el principal apoyo para ellos y lo que dicta el grupo es la norma a seguir porque necesitan ser apoyados por ellos.<\/p>\n<p>Para el adolescente es vital sentirse comprendido, sentirse apoyado y muchas veces los padres y los profesores lo que hacen es imponer su criterio y este es un momento en el que se rompe, todav\u00eda m\u00e1s se resquebraja la comunicaci\u00f3n, la relaci\u00f3n que tiene el adolescente con estas personas que son, a fin de cuentas, las personas que lo van a poder orientar y que van a poder prevenir, van a poder observar.<\/p>\n<p><iframe src=\"https:\/\/www.ivoox.com\/player_ej_141279127_6_1.html\" width=\"100%\" height=\"200\" frameborder=\"0\" allowfullscreen=\"\" scrolling=\"no\" loading=\"lazy\"><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00bfC\u00f3mo saber si su hijo tiene indicios de estar consumiendo drogas? \u00bfQu\u00e9 elementos debemos velar en el comportamiento de nuestros adolescentes? <\/p>\n","protected":false},"author":7,"featured_media":43404,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[9,8,1],"tags":[],"coauthors":[],"class_list":["post-43536","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-en-audio","category-noticia","category-sancti-spiritus"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.radiosanctispiritus.cu\/es\/wp-json\/wp\/v2\/posts\/43536","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.radiosanctispiritus.cu\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.radiosanctispiritus.cu\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.radiosanctispiritus.cu\/es\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.radiosanctispiritus.cu\/es\/wp-json\/wp\/v2\/comments?post=43536"}],"version-history":[{"count":0,"href":"https:\/\/www.radiosanctispiritus.cu\/es\/wp-json\/wp\/v2\/posts\/43536\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.radiosanctispiritus.cu\/es\/wp-json\/wp\/v2\/media\/43404"}],"wp:attachment":[{"href":"https:\/\/www.radiosanctispiritus.cu\/es\/wp-json\/wp\/v2\/media?parent=43536"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.radiosanctispiritus.cu\/es\/wp-json\/wp\/v2\/categories?post=43536"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.radiosanctispiritus.cu\/es\/wp-json\/wp\/v2\/tags?post=43536"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.radiosanctispiritus.cu\/es\/wp-json\/wp\/v2\/coauthors?post=43536"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}