{"id":42951,"date":"2025-02-25T16:57:15","date_gmt":"2025-02-25T21:57:15","guid":{"rendered":"https:\/\/www.radiosanctispiritus.cu\/es\/?p=42951"},"modified":"2025-09-30T12:42:04","modified_gmt":"2025-09-30T16:42:04","slug":"era-del-rock-blackberry-smoke","status":"publish","type":"post","link":"https:\/\/www.radiosanctispiritus.cu\/es\/era-del-rock-blackberry-smoke\/","title":{"rendered":"Blackberry Smoke"},"content":{"rendered":"<p>Blackberry Smoke es una banda estadounidense de rock sure\u00f1o formada en Atlanta, Georgia, en 2001. Su sonido mezcla country rock, blues y hard rock, con influencias de grupos como Lynyrd Skynyrd y The Allman Brothers Band. La formaci\u00f3n original inclu\u00eda a Charlie Starr (voz y guitarra), Paul Jackson (guitarra), Richard Turner (bajo), Brandon Still (teclados) y Brit Turner (bater\u00eda), quien falleci\u00f3 en marzo de 2024.<\/p>\n<p>La banda alcanz\u00f3 notoriedad con \u00e1lbumes como The Whippoorwill (2012), Holding All the Roses (2015) y Like an Arrow (2016), todos con buen desempe\u00f1o en las listas de Billboard. En 2023 grabaron Be Right Here, producido por Dave Cobb, con un enfoque m\u00e1s crudo y directo. Blackberry Smoke ha girado por Estados Unidos, Europa y Am\u00e9rica del Sur, compartiendo escenario con artistas como Guns N&#8217; Roses, ZZ Top y Eric Church.<\/p>\n<p><iframe src=\"https:\/\/www.ivoox.com\/player_ej_140408854_6_1.html?c1=daad89\" width=\"100%\" height=\"200\" frameborder=\"0\" scrolling=\"no\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mientras los movimientos p\u00e9lvicos de Elvis Presley provocaban en norteam\u00e9rica una situaci\u00f3n de esc\u00e1ndalo, a partir de 1954 el productor Sam Phillips aseguraba que la primera grabaci\u00f3n del rock and roll ya hab\u00eda sido realizada en sus estudios en 1951. En medio de esta imposible precisi\u00f3n hab\u00eda comenzado la Era del Rock , una estructura h\u00e1bilmente decorada con m\u00faltiples y ef\u00edmeras variantes del pop y fuertemente sostenida por un g\u00e9nero en constante evoluci\u00f3n, el Rock and Roll.<\/p>\n<p>Hoy en La Era del Rock: Blackberry Smoke<\/p>\n","protected":false},"author":4,"featured_media":42952,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"audio","meta":{"_acf_changed":false,"footnotes":""},"categories":[1393,10],"tags":[],"coauthors":[1883],"class_list":["post-42951","post","type-post","status-publish","format-audio","has-post-thumbnail","hentry","category-la-era-del-rock","category-programas-de-radio","post_format-post-format-audio"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.radiosanctispiritus.cu\/es\/wp-json\/wp\/v2\/posts\/42951","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.radiosanctispiritus.cu\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.radiosanctispiritus.cu\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.radiosanctispiritus.cu\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.radiosanctispiritus.cu\/es\/wp-json\/wp\/v2\/comments?post=42951"}],"version-history":[{"count":1,"href":"https:\/\/www.radiosanctispiritus.cu\/es\/wp-json\/wp\/v2\/posts\/42951\/revisions"}],"predecessor-version":[{"id":54863,"href":"https:\/\/www.radiosanctispiritus.cu\/es\/wp-json\/wp\/v2\/posts\/42951\/revisions\/54863"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.radiosanctispiritus.cu\/es\/wp-json\/wp\/v2\/media\/42952"}],"wp:attachment":[{"href":"https:\/\/www.radiosanctispiritus.cu\/es\/wp-json\/wp\/v2\/media?parent=42951"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.radiosanctispiritus.cu\/es\/wp-json\/wp\/v2\/categories?post=42951"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.radiosanctispiritus.cu\/es\/wp-json\/wp\/v2\/tags?post=42951"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.radiosanctispiritus.cu\/es\/wp-json\/wp\/v2\/coauthors?post=42951"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}