{"id":29900,"date":"2024-07-11T07:28:21","date_gmt":"2024-07-11T11:28:21","guid":{"rendered":"https:\/\/www.radiosanctispiritus.cu\/es\/?p=29900"},"modified":"2024-07-11T11:32:35","modified_gmt":"2024-07-11T15:32:35","slug":"precios-regulados-productos-desaparecidos","status":"publish","type":"post","link":"https:\/\/www.radiosanctispiritus.cu\/es\/precios-regulados-productos-desaparecidos\/","title":{"rendered":"Precios regulados,  productos desaparecidos"},"content":{"rendered":"<audio class=\"wp-audio-shortcode\" id=\"audio-29900-1\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"https:\/\/www.ivoox.com\/elsa-clo-11-7-24_md_131528831_wp_1.mp3?_=1\" \/><a href=\"https:\/\/www.ivoox.com\/elsa-clo-11-7-24_md_131528831_wp_1.mp3\" target=\"_blank\" rel=\"noopener\">https:\/\/www.ivoox.com\/elsa-clo-11-7-24_md_131528831_wp_1.mp3<\/a><\/audio>\n<p>De los 6 productos a los que el Ministerio de Finanzas y Precios, les regul\u00f3 el l\u00edmite m\u00e1ximo de los precios, parece ser que el pollo ha sido el primero en volar de la red donde m\u00e1s se comercializa: los actores econ\u00f3micos no estatales, esencialmente las MIPYMES.<\/p>\n<p>Al menos en Sancti Spiritus ese vuelo hacia la desaparici\u00f3n gradual\u00a0 de la venta parece marcar las tendencias. D\u00edas antes de la entrada en vigor de la resoluci\u00f3n 225 del 2024 que fij\u00f3 tarifas, ya el pollo troceado planeaba el vuelo que comienza a concretarse\u00a0 tan solo horas despu\u00e9s de que la norma comenz\u00f3 a regir en el pa\u00eds.<\/p>\n<p>Poco a poco comenz\u00f3 a escabullirse de los puntos de venta donde habitualmente se descongelaba a la espera de los consumidores, que ya andan preocupados por la suerte del producto, que aunque caro, hace meses alivia las comidas de quienes tienen respaldo financiero para comprarlo.<\/p>\n<p>Otros como el aceite que en algunos puntos estaba menos caro que lo aprobado en Resoluci\u00f3n, comenz\u00f3 a resbalarse hacia arriba a los cotos que la ley le permite, por m\u00e1s que se haya insistido que tal movimiento no deb\u00eda hacerse.<\/p>\n<p>Otros productos, a los que se les regul\u00f3 los precios,\u00a0 parecen no haberse enterado de que ya la norma est\u00e1 en vigor y que es de obligatorio cumplimiento.<\/p>\n<p>Justo tales distorsiones, sobre todo la de que desaparezcan las ofertas, son de los riesgos previstos en la arrancada de una resoluci\u00f3n que intenta, poner coto a la elevaci\u00f3n de los precios y la inflaci\u00f3n galopante.<\/p>\n<p>Ya que el sem\u00e1foro de la cotidianidad enciende y r\u00e1pido la luz roja, ser\u00e1 prudente tratar de que no se mantenga activa mucho tiempo y la violaci\u00f3n de la norma se establezca como ley y que como ocurre\u00a0 cada vez que el estado establece medidas relativas a los precios los productos se pierden de la vista de todos y se comercializa en las m\u00e1s oscuras redes del mercado informal donde sigue subiendo el precio mientras m\u00e1s manos lo toquen en la cadena de intermediarios y revendedores.<\/p>\n<p>Mucho m\u00e1s en casos como estos en que son las mipymes y otros actores econ\u00f3micos los due\u00f1os de la venta de esos productos de alta demanda porque el estado no tiene como hacerle contrapeso y el pollo por ejemplo que expende en sus tiendas en MLC\u00a0 es m\u00e1s caro que el que se vende por dinero cubano a trav\u00e9s de aquellos puntos.<\/p>\n<p>Sondeos realizados\u00a0 por esta propia comentarista entre los actores econ\u00f3micos no estatales en Sancti Spiritus han dado cuenta de que, seg\u00fan se inform\u00f3, en los encuentros\u00a0 entre estos y el estado, se vislumbr\u00f3 cierto consenso y aprobaci\u00f3n de los nuevos precios,\u00a0 lo cierto es que puertas afuera del encuentro, estos sostienen que tal limite de precios le genera p\u00e9rdidas, a\u00fan con la eliminaci\u00f3n del pago de aranceles y la consideraci\u00f3n de la tasa de cambio del d\u00f3lar en el mercado informal para la formaci\u00f3n de los precios.<\/p>\n<p>De una parte, han dicho, hay mercanc\u00edas acumuladas por meses adquiridas a una tarifa mayor para el USD cuando se le compara con la actual, que igual sigue en su vaiv\u00e9n del baja y sube y se torna complicado como punto de referencia para establecer una tarifa l\u00f3gica econ\u00f3micamente hablando.<\/p>\n<p>Seg\u00fan ha dicho la direcci\u00f3n provincial de finanzas y precios, m\u00e1s de 300 inspectores ser\u00e1n el n\u00facleo para el enfrentamiento integral que intenta caerle atr\u00e1s a los seis productos regulados ahora a la espera que se sumen los factores del Consejo Popular en la base y hasta el propio pueblo, que,\u00a0 como se ha demostrado en otros momentos, suele ser juez, parte y c\u00f3mplice de las violaciones, all\u00ed donde el control le aleja el plato cotidiano.<\/p>\n<p>La tarea es may\u00fascula ya que si\u00a0 la inspecci\u00f3n hoy ha sido incapaz de ganar la batalla de los precios, que ya se sabe se rigen por leyes econ\u00f3micas, le costar\u00e1 abarcar una medida nueva, que si bien no resuelve el dilema fundamental: que la mayor\u00eda de los salarios en Cuba no le lleguen ni por asomo a estos precios regulados, s\u00ed\u00a0 trata de poner un techo a la tendencia que hace rato acaba con los bolsillos de los menos favorecidos y engorda el de los comerciantes legales e ilegales.<\/p>\n<p>Ni 300 ni mil inspectores podr\u00e1n solos enfrentar la tarea que demanda millones de ojos \u00a0sistem\u00e1ticos para un mercado acostumbrado a evadir en impunidad los dictados de las leyes.<\/p>\n<p>Se trata de topar hasta un l\u00edmite para intentar mitigar la pesadilla de que un pollo lo vendan a un precio en un instante y a otro m\u00e1s caro un ratico despu\u00e9s apenas usted cierre y abra los ojos en el mismo punto de venta.<\/p>\n<p>Es, vi\u00e9ndolo en buen cubano, una curita para una patolog\u00eda como la inflaci\u00f3n galopante que necesita de terapias m\u00e1s integrales y radicales incluido el aumento de la producci\u00f3n a gran escala.<\/p>\n<p>Pero mientras llegan aquellas curas de caballo, hay que tratar de que al menos tras el pollo no emprendan vuelo los productos regulados y otros que son tambi\u00e9n de alta demanda y que al estar libres de la ley ya tratan de hacer contrapeso con tarifas m\u00e1s elevadas a las que rigen hasta hoy y que ya son inalcanzables.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La resoluci\u00f3n intenta poner coto a la elevaci\u00f3n de los precios y la inflaci\u00f3n galopante.<\/p>\n","protected":false},"author":14,"featured_media":29914,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[],"coauthors":[],"class_list":["post-29900","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sancti-spiritus"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.radiosanctispiritus.cu\/es\/wp-json\/wp\/v2\/posts\/29900","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.radiosanctispiritus.cu\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.radiosanctispiritus.cu\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.radiosanctispiritus.cu\/es\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/www.radiosanctispiritus.cu\/es\/wp-json\/wp\/v2\/comments?post=29900"}],"version-history":[{"count":0,"href":"https:\/\/www.radiosanctispiritus.cu\/es\/wp-json\/wp\/v2\/posts\/29900\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.radiosanctispiritus.cu\/es\/wp-json\/wp\/v2\/media\/29914"}],"wp:attachment":[{"href":"https:\/\/www.radiosanctispiritus.cu\/es\/wp-json\/wp\/v2\/media?parent=29900"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.radiosanctispiritus.cu\/es\/wp-json\/wp\/v2\/categories?post=29900"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.radiosanctispiritus.cu\/es\/wp-json\/wp\/v2\/tags?post=29900"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.radiosanctispiritus.cu\/es\/wp-json\/wp\/v2\/coauthors?post=29900"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}