{"id":26469,"date":"2024-05-05T05:30:33","date_gmt":"2024-05-05T09:30:33","guid":{"rendered":"https:\/\/www.radiosanctispiritus.cu\/es\/?p=26469"},"modified":"2024-05-04T21:42:21","modified_gmt":"2024-05-05T01:42:21","slug":"meteorologia-vaticina-incremento-de-la-lluvia-y-persistencia-del-calor","status":"publish","type":"post","link":"https:\/\/www.radiosanctispiritus.cu\/es\/meteorologia-vaticina-incremento-de-la-lluvia-y-persistencia-del-calor\/","title":{"rendered":"Meteorolog\u00eda vaticina incremento de la lluvia y persistencia del calor"},"content":{"rendered":"<p>El reci\u00e9n finalizado abril concluy\u00f3 en Sancti Sp\u00edritus con un marcado d\u00e9ficit de precipitaciones. Su l\u00e1mina media de lluvia suma 65,2 mil\u00edmetros y este a\u00f1o acumul\u00f3 menos del 30 por ciento de ese promedio, por lo cual clasific\u00f3 como un mes seco.<\/p>\n<audio class=\"wp-audio-shortcode\" id=\"audio-26469-1\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"https:\/\/www.ivoox.com\/mary-luz-al-dia-4-5-24_md_128438558_wp_1.mp3?_=1\" \/><a href=\"https:\/\/www.ivoox.com\/mary-luz-al-dia-4-5-24_md_128438558_wp_1.mp3\" target=\"_blank\" rel=\"noopener\">https:\/\/www.ivoox.com\/mary-luz-al-dia-4-5-24_md_128438558_wp_1.mp3<\/a><\/audio>\n<p>&nbsp;<\/p>\n<p>Seg\u00fan el resumen elaborado por el grupo de pron\u00f3sticos del Centro Meteorol\u00f3gico Provincial, en los \u00faltimos diez a\u00f1os \u00fanicamente este abril ha recibido semejante calificaci\u00f3n.<\/p>\n<p>Por territorios el municipio espirituano, junto a Yaguajay, Jatibonico y Fomento resultaron los m\u00e1s secos pues no alcanzaron siquiera el 10 por ciento de sus respectivas normas.<\/p>\n<p>En cuanto al comportamiento de las temperaturas, contrario a lo que se pudiera esperar dado el d\u00e9ficit de lluvias, \u00e9stas fueron ligeramente inferiores a lo usual para la fecha.<\/p>\n<p>Espec\u00edficamente en la Estaci\u00f3n Meteorol\u00f3gica ubicada por la zona del Aereopuerto espirituano, la temperatura m\u00ednima media bajo incluso dos grados Celsius en comparaci\u00f3n con su promedio hist\u00f3rico.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El reci\u00e9n finalizado abril concluy\u00f3 en Sancti Sp\u00edritus con un marcado d\u00e9ficit de precipitaciones. Su l\u00e1mina media de lluvia suma 65,2 mil\u00edmetros y este a\u00f1o acumul\u00f3 menos del 30 por ciento de ese promedio, por lo cual clasific\u00f3 como un mes seco.<\/p>\n","protected":false},"author":144,"featured_media":12591,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[9,8,1],"tags":[271,112,891],"coauthors":[],"class_list":["post-26469","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-en-audio","category-noticia","category-sancti-spiritus","tag-lluvias","tag-meteorologia","tag-temperatura"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.radiosanctispiritus.cu\/es\/wp-json\/wp\/v2\/posts\/26469","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.radiosanctispiritus.cu\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.radiosanctispiritus.cu\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.radiosanctispiritus.cu\/es\/wp-json\/wp\/v2\/users\/144"}],"replies":[{"embeddable":true,"href":"https:\/\/www.radiosanctispiritus.cu\/es\/wp-json\/wp\/v2\/comments?post=26469"}],"version-history":[{"count":0,"href":"https:\/\/www.radiosanctispiritus.cu\/es\/wp-json\/wp\/v2\/posts\/26469\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.radiosanctispiritus.cu\/es\/wp-json\/wp\/v2\/media\/12591"}],"wp:attachment":[{"href":"https:\/\/www.radiosanctispiritus.cu\/es\/wp-json\/wp\/v2\/media?parent=26469"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.radiosanctispiritus.cu\/es\/wp-json\/wp\/v2\/categories?post=26469"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.radiosanctispiritus.cu\/es\/wp-json\/wp\/v2\/tags?post=26469"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.radiosanctispiritus.cu\/es\/wp-json\/wp\/v2\/coauthors?post=26469"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}