{"id":18790,"date":"2023-11-18T18:54:56","date_gmt":"2023-11-18T23:54:56","guid":{"rendered":"https:\/\/www.radiosanctispiritus.cu\/es\/?p=18790"},"modified":"2023-11-18T18:55:29","modified_gmt":"2023-11-18T23:55:29","slug":"respetuosos-debates-distinguen-conferencia-la-nacion-y-la-emigracion","status":"publish","type":"post","link":"https:\/\/www.radiosanctispiritus.cu\/es\/respetuosos-debates-distinguen-conferencia-la-nacion-y-la-emigracion\/","title":{"rendered":"Respetuosos debates distinguen Conferencia La Naci\u00f3n y la Emigraci\u00f3n"},"content":{"rendered":"<p>La primera jornada de la IV Conferencia La Naci\u00f3n y la Emigraci\u00f3n que sesiona este fin de semana en La Habana, se caracteriza por debates respetuosos, abiertos, sin temas tab\u00faes y con libertad para plantear inquietudes, trascendi\u00f3 en un encuentro con la prensa acreditada.<\/p>\n<p>Laura Pujol, subdirectora general de la direcci\u00f3n de asuntos consulares y atenci\u00f3n a cubanos residentes en el exterior (Daccre), explic\u00f3 que la presencia en el plenario de nacionales radicados fuera de la Isla que estuvieron hace 45 a\u00f1os en el di\u00e1logo promovido por Fidel Castro, l\u00edder de la Revoluci\u00f3n, y de varias generaciones, es una muestra de los v\u00ednculos constantes de Cuba con ellos.<\/p>\n<p>La diplom\u00e1tica, en el Palacio de Convenciones de La Habana, aclar\u00f3 que luego de constatar las acreditaciones, la cifra de invitados es de 361, de 54 pa\u00edses, con la delegaci\u00f3n m\u00e1s numerosa procedente de Estados Unidos, y tambi\u00e9n de Espa\u00f1a, M\u00e9xico, Panam\u00e1, Francia e Italia, entre otras latitudes.<\/p>\n<p>Existe un inter\u00e9s especial en los paneles desarrollados en esta primera jornada, en la ma\u00f1ana el relacionado con los v\u00ednculos de Cuba y sus nacionales en el extranjero, a cargo de Carlos Fern\u00e1ndez de Coss\u00edo, vice ministro de Relaciones Exteriores, en el cual se explicaron las m\u00e1s recientes medidas migratorias, becas en la Isla para hijos de cubanos en el exterior, la extensi\u00f3n de la validez de los pasaportes, entre otras.<\/p>\n<p>No ha sido una interacci\u00f3n de reclamos y respuestas, sino un intercambio respetuoso donde todos se escuchan, fue sesi\u00f3n provechosa, productiva y de disfrute, que ratific\u00f3 la necesidad del encuentro f\u00edsico despu\u00e9s de 19 a\u00f1os, coment\u00f3 Pujol.<\/p>\n<div id=\"attachment_18792\" style=\"width: 610px\" class=\"wp-caption alignnone\"><img decoding=\"async\" aria-describedby=\"caption-attachment-18792\" class=\"size-medium wp-image-18792\" src=\"https:\/\/www.radiosanctispiritus.cu\/es\/wp-content\/uploads\/nacion01-600x347.jpg\" alt=\"\" width=\"600\" height=\"347\" srcset=\"https:\/\/www.radiosanctispiritus.cu\/es\/wp-content\/uploads\/nacion01-600x347.jpg 600w, https:\/\/www.radiosanctispiritus.cu\/es\/wp-content\/uploads\/nacion01-768x445.jpg 768w, https:\/\/www.radiosanctispiritus.cu\/es\/wp-content\/uploads\/nacion01-305x175.jpg 305w, https:\/\/www.radiosanctispiritus.cu\/es\/wp-content\/uploads\/nacion01.jpg 1000w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><p id=\"caption-attachment-18792\" class=\"wp-caption-text\">la Naci\u00f3n y la Emigraci\u00f3n. Foto: Ismael Francisco\/ Cubadebate.<\/p><\/div>\n<p>En la tarde Abel Prieto Jim\u00e9nez, presidente de Casa de las Am\u00e9rica, condujo el panel sobre cultura e identidad, en el cual artistas que residen en varios pa\u00edses del mundo expusieron mediante un producto audiovisual c\u00f3mo en su creaci\u00f3n est\u00e1 presente siempre Cuba, las ra\u00edces y la esencia.<\/p>\n<p>Existe consenso entre los participantes que la limitaci\u00f3n m\u00e1s importante para establecer v\u00ednculos con el pa\u00eds y contribuir a su desarrollo, est\u00e1n relacionadas con las afectaciones del bloqueo econ\u00f3mico, comercial y financiero que unilateralmente impone el gobierno de los Estados Unidos a la mayor de las Antillas.<\/p>\n<p>Para este domingo est\u00e1n previstos los paneles de comunicaci\u00f3n social y tecnolog\u00eda y el de desarrollo socioecon\u00f3mico e inversiones.<\/p>\n<p>Miguel D\u00edaz-Canel Berm\u00fadez, Primer Secretario del Comit\u00e9 Central del Partido Comunista de Cuba y Presidente de la Rep\u00fablica, y Bruno Rodr\u00edguez Parrilla, ministro de Relaciones Exteriores, han acompa\u00f1ado todo el tiempo a los asistentes a la Conferencia.<\/p>\n<div id=\"attachment_18793\" style=\"width: 610px\" class=\"wp-caption alignnone\"><img decoding=\"async\" aria-describedby=\"caption-attachment-18793\" class=\"size-medium wp-image-18793\" src=\"https:\/\/www.radiosanctispiritus.cu\/es\/wp-content\/uploads\/nacion10-600x318.jpg\" alt=\"\" width=\"600\" height=\"318\" srcset=\"https:\/\/www.radiosanctispiritus.cu\/es\/wp-content\/uploads\/nacion10-600x318.jpg 600w, https:\/\/www.radiosanctispiritus.cu\/es\/wp-content\/uploads\/nacion10-768x407.jpg 768w, https:\/\/www.radiosanctispiritus.cu\/es\/wp-content\/uploads\/nacion10.jpg 1000w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><p id=\"caption-attachment-18793\" class=\"wp-caption-text\">la Naci\u00f3n y la Emigraci\u00f3n. Foto: Ismael Francisco\/ Cubadebate.<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>La primera jornada de la IV Conferencia la Naci\u00f3n y la Emigraci\u00f3n que sesiona este fin de semana en La Habana, se caracteriza por debates respetuosos, abiertos, sin temas tab\u00faes y con libertad para plantear inquietudes.<\/p>\n","protected":false},"author":123,"featured_media":18791,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[3,8],"tags":[637,575,28,1036],"coauthors":[],"class_list":["post-18790","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cuba","category-noticia","tag-cuba-emigracion","tag-cuba-minrex","tag-miguel-diaz-canel","tag-nacion-y-emigracion"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.radiosanctispiritus.cu\/es\/wp-json\/wp\/v2\/posts\/18790","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.radiosanctispiritus.cu\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.radiosanctispiritus.cu\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.radiosanctispiritus.cu\/es\/wp-json\/wp\/v2\/users\/123"}],"replies":[{"embeddable":true,"href":"https:\/\/www.radiosanctispiritus.cu\/es\/wp-json\/wp\/v2\/comments?post=18790"}],"version-history":[{"count":0,"href":"https:\/\/www.radiosanctispiritus.cu\/es\/wp-json\/wp\/v2\/posts\/18790\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.radiosanctispiritus.cu\/es\/wp-json\/wp\/v2\/media\/18791"}],"wp:attachment":[{"href":"https:\/\/www.radiosanctispiritus.cu\/es\/wp-json\/wp\/v2\/media?parent=18790"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.radiosanctispiritus.cu\/es\/wp-json\/wp\/v2\/categories?post=18790"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.radiosanctispiritus.cu\/es\/wp-json\/wp\/v2\/tags?post=18790"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.radiosanctispiritus.cu\/es\/wp-json\/wp\/v2\/coauthors?post=18790"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}