{"id":15233,"date":"2023-08-17T21:12:30","date_gmt":"2023-08-18T01:12:30","guid":{"rendered":"https:\/\/www.radiosanctispiritus.cu\/es\/?p=15233"},"modified":"2023-08-17T21:12:30","modified_gmt":"2023-08-18T01:12:30","slug":"anuncia-estados-unidos-reapertura-en-cuba-de-oficina-para-temas-migratorios","status":"publish","type":"post","link":"https:\/\/www.radiosanctispiritus.cu\/es\/anuncia-estados-unidos-reapertura-en-cuba-de-oficina-para-temas-migratorios\/","title":{"rendered":"Anuncia Estados Unidos reapertura en Cuba de oficina para temas migratorios"},"content":{"rendered":"<p>El Departamento de Seguridad Nacional (DHS, por sus siglas en ingl\u00e9s), a trav\u00e9s de los Servicios de Ciudadan\u00eda e Inmigraci\u00f3n de Estados Unidos (Uscis), anunci\u00f3 este jueves la reapertura de una oficina internacional en La Habana, Cuba.<\/p>\n<p>La oficina en la capital cubana ayudar\u00e1 a esos servicios, incluida la realizaci\u00f3n de entrevistas y el procesamiento de casos pendientes del programa de reunificaci\u00f3n familiar, seg\u00fan el comunicado oficial.<\/p>\n<p>El secretario de Seguridad Nacional, Alejandro Mayorkas, dijo que la actual administraci\u00f3n est\u00e1 tomando medidas para reducir las entradas ilegales, \u201cnegar recursos a organizaciones de contrabando y simplificar el acceso a v\u00edas legales, seguras y ordenadas para quienes buscan ayuda humanitaria\u201d.<\/p>\n<p>Reabrir la oficina de campo de Uscis en La Habana -que de acuerdo con el anuncio proporcionar\u00e1 otros servicios limitados- \u201cnos ayuda a hacer precisamente eso\u201d, seg\u00fan Mayorkas.<\/p>\n<p>La Oficina de Campo de La Habana cerr\u00f3 oficialmente el 10 de diciembre de 2018, durante la administraci\u00f3n de Donald Trump, tras la suspensi\u00f3n a largo plazo de las operaciones en 2017 despu\u00e9s de que el Departamento de Estado ordenara a todo el personal no esencial y a sus familias salir de Cuba.<\/p>\n<p>Una medida que ocurri\u00f3 en el proceso de desmantelamiento de la embajada de Washington en La Habana tras acusaciones infundadas de la Casa Blanca sobre supuestos ataques s\u00f3nicos que afectaban a sus diplom\u00e1ticos en la isla<\/p>\n<p>Ello sirvi\u00f3, en realidad, para reforzar el bloqueo que por m\u00e1s de seis d\u00e9cadas impone con todo rigor el Gobierno de Estados Unidos, ya sean dem\u00f3cratas o republicanos, al pueblo de la mayor de las Antillas.<\/p>\n<p>La falsa narrativa construida entonces en torno a lo que llamaron \u201cs\u00edndrome misterioso\u201d fue desmontada no solo por cient\u00edficos cubanos, sino tambi\u00e9n estadounidenses.<\/p>\n<p>El 9 de junio de 2022, el DHS inform\u00f3 que reanudar\u00eda sus operaciones bajo el programa de reunificaci\u00f3n familiar (Cuban Family Reunification Parole), que se estableci\u00f3 en 2007 para proporcionar una v\u00eda segura y ordenada de migraci\u00f3n hacia Estados Unidos.<\/p>\n<p>\u201cOjal\u00e1 que la oficina esa sirva para que se puedan procesar en realidad todas las visas dentro de Cuba y aquellos que desean viajar a Estados Unidos no tengan que ir a un tercer pa\u00eds con todos los gastos que eso implica\u201d, expres\u00f3 en una directa en redes sociales el activista Carlos Lazo, coordinador del movimiento Puentes de Amor.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Departamento de Seguridad Nacional, por sus siglas en ingl\u00e9s), a trav\u00e9s de los Servicios de Ciudadan\u00eda e Inmigraci\u00f3n de Estados Unidos, anunci\u00f3 este jueves la reapertura de una oficina internacional en La Habana, Cuba.<\/p>\n","protected":false},"author":22,"featured_media":15234,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[3,8],"tags":[98,637,285],"coauthors":[],"class_list":["post-15233","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cuba","category-noticia","tag-cuba-ee-uu","tag-cuba-emigracion","tag-relaciones-cuba-ee-uu"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.radiosanctispiritus.cu\/es\/wp-json\/wp\/v2\/posts\/15233","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.radiosanctispiritus.cu\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.radiosanctispiritus.cu\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.radiosanctispiritus.cu\/es\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/www.radiosanctispiritus.cu\/es\/wp-json\/wp\/v2\/comments?post=15233"}],"version-history":[{"count":0,"href":"https:\/\/www.radiosanctispiritus.cu\/es\/wp-json\/wp\/v2\/posts\/15233\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.radiosanctispiritus.cu\/es\/wp-json\/wp\/v2\/media\/15234"}],"wp:attachment":[{"href":"https:\/\/www.radiosanctispiritus.cu\/es\/wp-json\/wp\/v2\/media?parent=15233"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.radiosanctispiritus.cu\/es\/wp-json\/wp\/v2\/categories?post=15233"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.radiosanctispiritus.cu\/es\/wp-json\/wp\/v2\/tags?post=15233"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.radiosanctispiritus.cu\/es\/wp-json\/wp\/v2\/coauthors?post=15233"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}