{"id":13266,"date":"2023-06-22T15:21:37","date_gmt":"2023-06-22T19:21:37","guid":{"rendered":"https:\/\/www.radiosanctispiritus.cu\/es\/?p=13266"},"modified":"2023-06-22T15:21:37","modified_gmt":"2023-06-22T19:21:37","slug":"trinidad-de-cuba-el-sudor-de-la-esclavitud-convertido-en-riqueza-en-la-colonia-fotos","status":"publish","type":"post","link":"https:\/\/www.radiosanctispiritus.cu\/es\/trinidad-de-cuba-el-sudor-de-la-esclavitud-convertido-en-riqueza-en-la-colonia-fotos\/","title":{"rendered":"Trinidad de Cuba: El sudor de la esclavitud convertido en riqueza en la colonia (+Fotos)"},"content":{"rendered":"<p>La Trinidad de Cuba, Patrimonio Cultural de la Humanidad, conserva hoy majestuosos testimonios de la arquitectura de los siglos XVII al XIX cuyo origen fue fruto del desarrollo de la industria azucarera por peninsulares y nacionales, y la esclavitud ofrec\u00eda su vida.<\/p>\n<p>En el Valle de los Ingenios, al pie de las monta\u00f1as de Guamuhaya o Escambray, tambi\u00e9n con el titulo otorgado por la Unesco en 1988, florecieron casas haciendas, palacetes y trapiches que requirieron de mano de obra esclava.<\/p>\n<p>Entre los conjuntos productivos -vivienda e ingenio- m\u00e1s conservados est\u00e1n Manaca-Iznaga, Buena Vista, Delicias, Gu\u00e1imaro y Magua, donde predomina la arquitectura neocl\u00e1sica -mezcla de estilos- y acomodo al clima de la localidad.<\/p>\n<p><img decoding=\"async\" class=\"alignnone size-full wp-image-502285 lazyloaded\" src=\"https:\/\/www.prensa-latina.cu\/wp-content\/uploads\/2023\/06\/Ingenio-Buena-Vista-Trinidad.jpg\" sizes=\"(max-width: 785px) 100vw, 785px\" srcset=\"https:\/\/www.prensa-latina.cu\/wp-content\/uploads\/2023\/06\/Ingenio-Buena-Vista-Trinidad.jpg 785w, https:\/\/www.prensa-latina.cu\/wp-content\/uploads\/2023\/06\/Ingenio-Buena-Vista-Trinidad-500x306.jpg 500w, https:\/\/www.prensa-latina.cu\/wp-content\/uploads\/2023\/06\/Ingenio-Buena-Vista-Trinidad-150x92.jpg 150w, https:\/\/www.prensa-latina.cu\/wp-content\/uploads\/2023\/06\/Ingenio-Buena-Vista-Trinidad-768x470.jpg 768w\" alt=\"\" width=\"785\" height=\"480\" data-ll-status=\"loaded\" \/>Cada una de estas lujosas haciendas mantienen sus propias f\u00e1bulas de felicidad entre los amos y de maltrato y vejaciones entre la prole negra, de mujeres, hombres e hijos separados, que nunca fueron mansos, su rebeld\u00eda perdura en la historia.<\/p>\n<p>La mayor\u00eda con sus pozos y torres que serv\u00edan de vigilancia y hermosas leyendas como la de la torre campanario de Manaca-Iznaga, edificada en las primeras dos d\u00e9cadas del siglo XIX, y que en la actualidad es s\u00edmbolo del desarrollo azucarero de Cuba en tiempo de la colonia.<\/p>\n<p>Desde esa atalaya de estilo romano de unos 45 metros de altura, con ventanas laterales y 184 escalones, se domina todo a su alrededor y donde otrora se vigilaba el laboreo y a los esclavos.<\/p>\n<p>El historiador oficial de la tercera villa patrimonial Carlos Joaqu\u00edn Zerquera y Fern\u00e1ndez de Lara (1926-2009), reconoci\u00f3 a este reportero que el esplendor del Valle lleg\u00f3 al transformarse el panorama rural a costa del sudor y el sufrimiento de cientos de esclavos.<\/p>\n<p><img decoding=\"async\" class=\"alignnone size-full wp-image-502289 lazyloaded\" src=\"https:\/\/www.prensa-latina.cu\/wp-content\/uploads\/2023\/06\/Carlos-Joaquin-1-1.jpg\" sizes=\"(max-width: 1024px) 100vw, 1024px\" srcset=\"https:\/\/www.prensa-latina.cu\/wp-content\/uploads\/2023\/06\/Carlos-Joaquin-1-1.jpg 1024w, https:\/\/www.prensa-latina.cu\/wp-content\/uploads\/2023\/06\/Carlos-Joaquin-1-1-500x375.jpg 500w, https:\/\/www.prensa-latina.cu\/wp-content\/uploads\/2023\/06\/Carlos-Joaquin-1-1-150x113.jpg 150w, https:\/\/www.prensa-latina.cu\/wp-content\/uploads\/2023\/06\/Carlos-Joaquin-1-1-768x576.jpg 768w\" alt=\"\" width=\"1024\" height=\"768\" data-ll-status=\"loaded\" \/>En nuestra conversaci\u00f3n dijo que los primeros esclavos africanos llegaron al centro de la isla por el sur de la provincia de Sancti Sp\u00edritus, a trav\u00e9s de los r\u00edos, en especial el Agabama y el Guaurabo, aunque tambi\u00e9n proven\u00edan de otros puntos del pa\u00eds.<\/p>\n<p>Los colonizadores con sus m\u00e9todos de explotaci\u00f3n de los ind\u00edgenas pr\u00e1cticamente los exterminaron, en unas dos o tres d\u00e9cadas se redujeron y la opci\u00f3n ya experimentada en otras naciones era abrir la ruta de la esclavitud.<\/p>\n<p><img decoding=\"async\" class=\"alignnone size-full wp-image-502284 lazyloaded\" src=\"https:\/\/www.prensa-latina.cu\/wp-content\/uploads\/2023\/06\/Esclavos.jpg\" sizes=\"(max-width: 854px) 100vw, 854px\" srcset=\"https:\/\/www.prensa-latina.cu\/wp-content\/uploads\/2023\/06\/Esclavos.jpg 854w, https:\/\/www.prensa-latina.cu\/wp-content\/uploads\/2023\/06\/Esclavos-500x253.jpg 500w, https:\/\/www.prensa-latina.cu\/wp-content\/uploads\/2023\/06\/Esclavos-150x76.jpg 150w, https:\/\/www.prensa-latina.cu\/wp-content\/uploads\/2023\/06\/Esclavos-768x388.jpg 768w\" alt=\"\" width=\"854\" height=\"432\" data-ll-status=\"loaded\" \/>Aunque Zerquera de Lara NO lo afirm\u00f3, consideraba que la primera mano de obra extranjera que lleg\u00f3 a la Mayor de las Antillas fue en el siglo XVI proveniente de Yucat\u00e1n, M\u00e9xico.<\/p>\n<p>Prensa Latina conoci\u00f3 que en los archivos locales existen documentos de la presencia esclava en forma temprana, de sublevaciones en Sancti Sp\u00edritus y Trinidad en 1533, 1538 y 1616, apoyadas por negros libres y cimarrones.<\/p>\n<p>En poco m\u00e1s de un siglo la poblaci\u00f3n negra en la villa trinitaria era de mil 207 personas y en 1740 se reportaban cinco mil 234 sometidos a la servidumbre.<\/p>\n<p><img decoding=\"async\" class=\"alignnone size-full wp-image-502286 lazyloaded\" src=\"https:\/\/www.prensa-latina.cu\/wp-content\/uploads\/2023\/06\/valle-4.jpg\" sizes=\"(max-width: 1024px) 100vw, 1024px\" srcset=\"https:\/\/www.prensa-latina.cu\/wp-content\/uploads\/2023\/06\/valle-4.jpg 1024w, https:\/\/www.prensa-latina.cu\/wp-content\/uploads\/2023\/06\/valle-4-500x332.jpg 500w, https:\/\/www.prensa-latina.cu\/wp-content\/uploads\/2023\/06\/valle-4-150x100.jpg 150w, https:\/\/www.prensa-latina.cu\/wp-content\/uploads\/2023\/06\/valle-4-768x510.jpg 768w\" alt=\"\" width=\"1024\" height=\"680\" data-ll-status=\"loaded\" \/>A mediados del siglo XVIII hab\u00edan 25 trapiches y muy pr\u00f3ximo a la \u00faltima d\u00e9cada de ese periodo, se reportaban 40 f\u00e1bricas que elaboraban unas de 60 mil arrobas de az\u00facar mascabada -cruda- y unas 700 botijas de miel.<\/p>\n<p>A Cuba fueron tra\u00eddos negros de todos los sitios del \u00c1frica subsahariana, lo cual reafirma una gran diversidad de grupos \u00e9tnicos de ese continente, concurrentes en el proceso de transculturaci\u00f3n y mestizaje que conforman lo nacional cubano.<\/p>\n<p>No solo el az\u00facar y el caf\u00e9 conocieron del trabajo esclavo africano, este tambi\u00e9n alcanz\u00f3 la construcci\u00f3n de v\u00edas de comunicaci\u00f3n, fortificaciones y grandes mansiones en las ciudades.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Trinidad de Cuba, Patrimonio Cultural de la Humanidad, conserva hoy majestuosos testimonios de la arquitectura de los siglos XVII al XIX cuyo origen fue fruto del desarrollo de la industria azucarera por peninsulares y nacionales, y la esclavitud ofrec\u00eda su vida. <\/p>\n","protected":false},"author":22,"featured_media":13267,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[6,8,1],"tags":[],"coauthors":[],"class_list":["post-13266","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura","category-noticia","category-sancti-spiritus"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.radiosanctispiritus.cu\/es\/wp-json\/wp\/v2\/posts\/13266","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.radiosanctispiritus.cu\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.radiosanctispiritus.cu\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.radiosanctispiritus.cu\/es\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/www.radiosanctispiritus.cu\/es\/wp-json\/wp\/v2\/comments?post=13266"}],"version-history":[{"count":0,"href":"https:\/\/www.radiosanctispiritus.cu\/es\/wp-json\/wp\/v2\/posts\/13266\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.radiosanctispiritus.cu\/es\/wp-json\/wp\/v2\/media\/13267"}],"wp:attachment":[{"href":"https:\/\/www.radiosanctispiritus.cu\/es\/wp-json\/wp\/v2\/media?parent=13266"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.radiosanctispiritus.cu\/es\/wp-json\/wp\/v2\/categories?post=13266"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.radiosanctispiritus.cu\/es\/wp-json\/wp\/v2\/tags?post=13266"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.radiosanctispiritus.cu\/es\/wp-json\/wp\/v2\/coauthors?post=13266"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}